{"id":15546,"date":"2023-06-12T12:39:02","date_gmt":"2023-06-12T10:39:02","guid":{"rendered":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano.jpeg"},"modified":"2023-06-12T12:39:02","modified_gmt":"2023-06-12T10:39:02","slug":"podio-carpa-lago-faetano-2","status":"inherit","type":"attachment","link":"https:\/\/www.cons.sm\/en\/podio-carpa-lago-faetano-2\/","title":{"rendered":"podio carpa lago faetano"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-15546","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-300x300.jpeg 300w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-1024x1024.jpeg 1024w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-150x150.jpeg 150w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-768x768.jpeg 768w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-1536x1536.jpeg 1536w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-1100x1100.jpeg 1100w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-520x520.jpeg 520w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-1920x1920.jpeg 1920w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-130x130.jpeg 130w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-200x200.jpeg 200w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-100x100.jpeg 100w, https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":2048,"file":"2023\/06\/podio-carpa-lago-faetano.jpeg","filesize":532224,"sizes":{"medium":{"file":"podio-carpa-lago-faetano-300x300.jpeg","width":300,"height":300,"filesize":21494,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-300x300.jpeg"},"large":{"file":"podio-carpa-lago-faetano-1024x1024.jpeg","width":1024,"height":1024,"filesize":186340,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-1024x1024.jpeg"},"thumbnail":{"file":"podio-carpa-lago-faetano-150x150.jpeg","width":150,"height":150,"filesize":6622,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-150x150.jpeg"},"medium_large":{"file":"podio-carpa-lago-faetano-768x768.jpeg","width":768,"height":768,"filesize":112329,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-768x768.jpeg"},"1536x1536":{"file":"podio-carpa-lago-faetano-1536x1536.jpeg","width":1536,"height":1536,"filesize":384041,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-1536x1536.jpeg"},"news-big":{"file":"podio-carpa-lago-faetano-1100x1100.jpeg","width":1100,"height":1100,"filesize":217139,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-1100x1100.jpeg"},"news-small":{"file":"podio-carpa-lago-faetano-520x520.jpeg","width":520,"height":520,"filesize":55766,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-520x520.jpeg"},"landscape":{"file":"podio-carpa-lago-faetano-1920x1920.jpeg","width":1920,"height":1920,"filesize":554077,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-1920x1920.jpeg"},"sponsor-list":{"file":"podio-carpa-lago-faetano-130x130.jpeg","width":130,"height":130,"filesize":5373,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-130x130.jpeg"},"games-federations-list":{"file":"podio-carpa-lago-faetano-200x200.jpeg","width":200,"height":200,"filesize":10512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-200x200.jpeg"},"federations-list":{"file":"podio-carpa-lago-faetano-100x100.jpeg","width":100,"height":100,"filesize":3499,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-100x100.jpeg"},"cover-logo":{"file":"podio-carpa-lago-faetano-130x130.jpeg","width":130,"height":130,"filesize":5373,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano-130x130.jpeg"},"full":{"file":"podio-carpa-lago-faetano.jpeg","width":2048,"height":2048,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.cons.sm\/wp-content\/uploads\/2023\/06\/podio-carpa-lago-faetano.jpeg","_links":{"self":[{"href":"https:\/\/www.cons.sm\/en\/wp-json\/wp\/v2\/media\/15546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cons.sm\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.cons.sm\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.cons.sm\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cons.sm\/en\/wp-json\/wp\/v2\/comments?post=15546"}]}}